{"id":5893,"date":"2021-07-30T10:21:10","date_gmt":"2021-07-30T10:21:10","guid":{"rendered":"https:\/\/www.hermanosmasa.com\/grandes-surfaces\/"},"modified":"2021-07-30T12:34:45","modified_gmt":"2021-07-30T12:34:45","slug":"grandes-surfaces","status":"publish","type":"page","link":"https:\/\/www.hermanosmasa.com\/fr\/grandes-surfaces\/","title":{"rendered":"Grandes surfaces"},"content":{"rendered":"<p>[et_pb_section fb_built=\u00a0\u00bb1&Prime; _builder_version=\u00a0\u00bb4.8.1&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb custom_margin=\u00a0\u00bb0px||0px||false|false\u00a0\u00bb custom_padding=\u00a0\u00bb0px||0px||false|false\u00a0\u00bb][et_pb_row column_structure=\u00a0\u00bb1_4,1_2,1_4&Prime; make_equal=\u00a0\u00bbon\u00a0\u00bb _builder_version=\u00a0\u00bb4.9.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb width=\u00a0\u00bb100%\u00a0\u00bb max_width=\u00a0\u00bb2560px\u00a0\u00bb custom_margin=\u00a0\u00bb0px||0px||false|false\u00a0\u00bb custom_padding=\u00a0\u00bb0px||0px||false|false\u00a0\u00bb][et_pb_column type=\u00a0\u00bb1_4&Prime; _builder_version=\u00a0\u00bb4.9.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb background_image=\u00a0\u00bbhttps:\/\/www.hermanosmasa.com\/wp-content\/uploads\/2021\/06\/grandes-superficies.jpg\u00a0\u00bb][\/et_pb_column][et_pb_column type=\u00a0\u00bb1_2&Prime; _builder_version=\u00a0\u00bb4.8.1&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb custom_padding=\u00a0\u00bb75px|10px|75px|10px|false|false\u00a0\u00bb][et_pb_text _builder_version=\u00a0\u00bb4.8.1&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb text_font_size=\u00a0\u00bb25px\u00a0\u00bb header_font_size=\u00a0\u00bb42px\u00a0\u00bb header_line_height=\u00a0\u00bb1.2em\u00a0\u00bb header_2_font_size=\u00a0\u00bb36px\u00a0\u00bb header_2_line_height=\u00a0\u00bb1.2em\u00a0\u00bb custom_padding=\u00a0\u00bb||||false|false\u00a0\u00bb hover_enabled=\u00a0\u00bb0&Prime; sticky_enabled=\u00a0\u00bb0&Prime;]<\/p>\n<h1><strong>Grandes surfaces<\/strong><\/h1>\n<p>[\/et_pb_text][et_pb_text _builder_version=\u00a0\u00bb4.8.1&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb text_font_size=\u00a0\u00bb25px\u00a0\u00bb header_font_size=\u00a0\u00bb42px\u00a0\u00bb header_line_height=\u00a0\u00bb1.2em\u00a0\u00bb header_2_font_size=\u00a0\u00bb36px\u00a0\u00bb header_2_line_height=\u00a0\u00bb1.2em\u00a0\u00bb custom_padding=\u00a0\u00bb||||false|false\u00a0\u00bb hover_enabled=\u00a0\u00bb0&Prime; sticky_enabled=\u00a0\u00bb0&Prime;]<\/p>\n<h2>Nous distribuons nos produits dans diff\u00e9rents grands magasins et supermarch\u00e9s, qui depuis des ann\u00e9es nous choisissent pour nos avantages:<\/h2>\n<p>[\/et_pb_text][et_pb_text _builder_version=\u00a0\u00bb4.9.7&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb text_font_size=\u00a0\u00bb25px\u00a0\u00bb header_font_size=\u00a0\u00bb42px\u00a0\u00bb header_line_height=\u00a0\u00bb1.2em\u00a0\u00bb header_2_font_size=\u00a0\u00bb36px\u00a0\u00bb header_2_line_height=\u00a0\u00bb1.2em\u00a0\u00bb custom_padding=\u00a0\u00bb||||false|false\u00a0\u00bb hover_enabled=\u00a0\u00bb0&Prime; sticky_enabled=\u00a0\u00bb0&Prime;]<\/p>\n<ul>\n<li><strong>Etiquetage et bac sp\u00e9cifique.<\/strong> Le produit de chaque client aura sa propre personnalit\u00e9 de marque gr\u00e2ce \u00e0 un \u00e9tiquetage exclusivement con\u00e7u.<\/li>\n<li><strong>Syst\u00e8me de commande EDI.<\/strong> Les savoirs traditionnels appliqu\u00e9s \u00e0 l&rsquo;obtention du meilleur produit ne sont pas incompatibles avec les avanc\u00e9es technologiques qui nous permettent de le distribuer avec plus d&rsquo;efficacit\u00e9 et d&rsquo;agilit\u00e9. C&rsquo;est pourquoi nous avons mis en place le syst\u00e8me EDI pour la r\u00e9ception des commandes, avec tous les avantages que cela implique pour nos clients.<\/li>\n<li><strong>Distribution sur les plateformes et par succursales.<\/strong> Nous nous adaptons \u00e0 la structure logistique de chaque client, de mani\u00e8re \u00e0 pouvoir effectuer des exp\u00e9ditions \u00e0 la fois vers leurs plateformes de distribution et vers chacun des points \u00e0 distribuer, toujours adapt\u00e9es \u00e0 leurs besoins.<\/li>\n<li><strong>Grande r\u00e9activit\u00e9.<\/strong> En cas d&rsquo;impr\u00e9vu, aux dates les plus sollicit\u00e9es, et \u00e0 tout moment, notre infrastructure et notre \u00e9quipe humaine nous rendent capables de r\u00e9pondre \u00e0 nos clients.<\/li>\n<\/ul>\n<p>[\/et_pb_text][et_pb_button button_url=\u00a0\u00bbhttps:\/\/agneaudelait.fr\/contact\/\u00a0\u00bb button_text=\u00a0\u00bbDemandez plus d&rsquo;informations\u00a0\u00bb button_alignment=\u00a0\u00bbcenter\u00a0\u00bb _builder_version=\u00a0\u00bb4.8.1&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb][\/et_pb_button][\/et_pb_column][et_pb_column type=\u00a0\u00bb1_4&Prime; _builder_version=\u00a0\u00bb4.8.1&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb][\/et_pb_column][\/et_pb_row][\/et_pb_section]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Grandes surfacesNous distribuons nos produits dans diff\u00e9rents grands magasins et supermarch\u00e9s, qui depuis des ann\u00e9es nous choisissent pour nos avantages: Etiquetage et bac sp\u00e9cifique. Le produit de chaque client aura sa propre personnalit\u00e9 de marque gr\u00e2ce \u00e0 un \u00e9tiquetage exclusivement con\u00e7u. Syst\u00e8me de commande EDI. Les savoirs traditionnels appliqu\u00e9s \u00e0 l&rsquo;obtention du meilleur produit ne [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":2,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_et_pb_use_builder":"on","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"class_list":["post-5893","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/www.hermanosmasa.com\/fr\/wp-json\/wp\/v2\/pages\/5893","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.hermanosmasa.com\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.hermanosmasa.com\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.hermanosmasa.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.hermanosmasa.com\/fr\/wp-json\/wp\/v2\/comments?post=5893"}],"version-history":[{"count":9,"href":"https:\/\/www.hermanosmasa.com\/fr\/wp-json\/wp\/v2\/pages\/5893\/revisions"}],"predecessor-version":[{"id":6031,"href":"https:\/\/www.hermanosmasa.com\/fr\/wp-json\/wp\/v2\/pages\/5893\/revisions\/6031"}],"wp:attachment":[{"href":"https:\/\/www.hermanosmasa.com\/fr\/wp-json\/wp\/v2\/media?parent=5893"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}