{"id":5916,"date":"2021-07-30T10:34:51","date_gmt":"2021-07-30T10:34:51","guid":{"rendered":"https:\/\/www.hermanosmasa.com\/industrie-alimentaire\/"},"modified":"2021-07-30T12:34:45","modified_gmt":"2021-07-30T12:34:45","slug":"industrie-alimentaire","status":"publish","type":"page","link":"https:\/\/www.hermanosmasa.com\/fr\/industrie-alimentaire\/","title":{"rendered":"Industrie alimentaire"},"content":{"rendered":"<p>[et_pb_section fb_built=\u00a0\u00bb1&Prime; _builder_version=\u00a0\u00bb4.8.1&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb custom_margin=\u00a0\u00bb0px||0px||false|false\u00a0\u00bb custom_padding=\u00a0\u00bb0px||0px||false|false\u00a0\u00bb][et_pb_row column_structure=\u00a0\u00bb1_4,1_2,1_4&Prime; make_equal=\u00a0\u00bbon\u00a0\u00bb _builder_version=\u00a0\u00bb4.9.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb width=\u00a0\u00bb100%\u00a0\u00bb max_width=\u00a0\u00bb2560px\u00a0\u00bb custom_margin=\u00a0\u00bb0px||0px||false|false\u00a0\u00bb custom_padding=\u00a0\u00bb0px||0px||false|false\u00a0\u00bb hover_enabled=\u00a0\u00bb0&Prime; sticky_enabled=\u00a0\u00bb0&Prime;][et_pb_column type=\u00a0\u00bb1_4&Prime; _builder_version=\u00a0\u00bb4.9.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb background_image=\u00a0\u00bbhttps:\/\/www.hermanosmasa.com\/wp-content\/uploads\/2021\/06\/industria.jpg\u00a0\u00bb hover_enabled=\u00a0\u00bb0&Prime; title_text=\u00a0\u00bbindustria\u00a0\u00bb sticky_enabled=\u00a0\u00bb0&Prime;][\/et_pb_column][et_pb_column type=\u00a0\u00bb1_2&Prime; _builder_version=\u00a0\u00bb4.8.1&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb custom_padding=\u00a0\u00bb75px|10px|75px|10px|false|false\u00a0\u00bb][et_pb_text _builder_version=\u00a0\u00bb4.8.1&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb text_font_size=\u00a0\u00bb25px\u00a0\u00bb header_font_size=\u00a0\u00bb42px\u00a0\u00bb header_line_height=\u00a0\u00bb1.2em\u00a0\u00bb header_2_font_size=\u00a0\u00bb36px\u00a0\u00bb header_2_line_height=\u00a0\u00bb1.2em\u00a0\u00bb custom_padding=\u00a0\u00bb||||false|false\u00a0\u00bb]<\/p>\n<h1><strong>Industries alimentaires<\/strong><\/h1>\n<p>[\/et_pb_text][et_pb_text _builder_version=\u00a0\u00bb4.8.1&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb text_font_size=\u00a0\u00bb25px\u00a0\u00bb header_font_size=\u00a0\u00bb42px\u00a0\u00bb header_line_height=\u00a0\u00bb1.2em\u00a0\u00bb header_2_font_size=\u00a0\u00bb36px\u00a0\u00bb header_2_line_height=\u00a0\u00bb1.2em\u00a0\u00bb custom_padding=\u00a0\u00bb||||false|false\u00a0\u00bb]<\/p>\n<h2>Les industries alimentaires ont besoin et appr\u00e9cient un fournisseur avec la capacit\u00e9, la fiabilit\u00e9 et la rapidit\u00e9 dont ils ont besoin pour r\u00e9pondre aux besoins de leurs cadences de production. Fr\u00e8res Masa vous apporte:<\/h2>\n<p>[\/et_pb_text][et_pb_text _builder_version=\u00a0\u00bb4.8.1&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb text_font_size=\u00a0\u00bb25px\u00a0\u00bb header_font_size=\u00a0\u00bb42px\u00a0\u00bb header_line_height=\u00a0\u00bb1.2em\u00a0\u00bb header_2_font_size=\u00a0\u00bb36px\u00a0\u00bb header_2_line_height=\u00a0\u00bb1.2em\u00a0\u00bb custom_padding=\u00a0\u00bb||||false|false\u00a0\u00bb]<\/p>\n<ul>\n<li><strong>Achetez en canal sans interm\u00e9diaires.<\/strong> Acheter directement aupr\u00e8s de l&rsquo;agriculteur ou de la coop\u00e9rative de confiance. Ensuite, nous nous occupons de l&rsquo;ensemble du processus, \u00e0 la fois la supervision de l&rsquo;abattage de l&rsquo;animal et la d\u00e9coupe demand\u00e9e, afin que toutes les \u00e9tapes soient mieux ma\u00eetris\u00e9es.<\/li>\n<li><strong>Entrep\u00f4t congel\u00e9.<\/strong> Apr\u00e8s la d\u00e9coupe, nous disposons d&rsquo;un tunnel de cong\u00e9lation et de chambres froides afin de pouvoir contr\u00f4ler la qualit\u00e9 et garantir la cha\u00eene du froid en toute fiabilit\u00e9.<\/li>\n<li><strong>Coup\u00e9 \u00e0 la taille.<\/strong> Nous r\u00e9alisons des coupes au gr\u00e9 du client, de la plus classique \u00e0 une coupe beaucoup plus \u00e9labor\u00e9e, demand\u00e9e pour la pr\u00e9paration de nouveaux plats. Nos coupeurs experts sont form\u00e9s pour r\u00e9pondre \u00e0 toute demande.<\/li>\n<li><strong>Accompagnement de nos sp\u00e9cialistes bouchers.<\/strong> Nos collaborateurs travaillent comme sp\u00e9cialistes de la viande depuis plus de 20 ans, ils peuvent donc vous apporter des conseils sur les coupes et d\u00e9coupes, ainsi qu&rsquo;un savoir-faire totalement artisanal, qui nous identifie. Toute notre exp\u00e9rience est \u00e0 votre service.<\/li>\n<\/ul>\n<p>[\/et_pb_text][et_pb_button button_url=\u00a0\u00bbhttps:\/\/agneaudelait.fr\/contact\/\u00a0\u00bb button_text=\u00a0\u00bbDemandez plus d&rsquo;informations\u00a0\u00bb button_alignment=\u00a0\u00bbcenter\u00a0\u00bb _builder_version=\u00a0\u00bb4.8.1&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb][\/et_pb_button][\/et_pb_column][et_pb_column type=\u00a0\u00bb1_4&Prime; _builder_version=\u00a0\u00bb4.8.1&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb][\/et_pb_column][\/et_pb_row][\/et_pb_section]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Industries alimentairesLes industries alimentaires ont besoin et appr\u00e9cient un fournisseur avec la capacit\u00e9, la fiabilit\u00e9 et la rapidit\u00e9 dont ils ont besoin pour r\u00e9pondre aux besoins de leurs cadences de production. Fr\u00e8res Masa vous apporte: Achetez en canal sans interm\u00e9diaires. Acheter directement aupr\u00e8s de l&rsquo;agriculteur ou de la coop\u00e9rative de confiance. Ensuite, nous nous occupons [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":4,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_et_pb_use_builder":"on","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"class_list":["post-5916","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/www.hermanosmasa.com\/fr\/wp-json\/wp\/v2\/pages\/5916","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.hermanosmasa.com\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.hermanosmasa.com\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.hermanosmasa.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.hermanosmasa.com\/fr\/wp-json\/wp\/v2\/comments?post=5916"}],"version-history":[{"count":6,"href":"https:\/\/www.hermanosmasa.com\/fr\/wp-json\/wp\/v2\/pages\/5916\/revisions"}],"predecessor-version":[{"id":6032,"href":"https:\/\/www.hermanosmasa.com\/fr\/wp-json\/wp\/v2\/pages\/5916\/revisions\/6032"}],"wp:attachment":[{"href":"https:\/\/www.hermanosmasa.com\/fr\/wp-json\/wp\/v2\/media?parent=5916"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}