{"id":5966,"date":"2021-04-27T11:38:04","date_gmt":"2021-07-30T11:59:35","guid":{"rendered":"https:\/\/www.hermanosmasa.com\/tienda\/carre-enfant\/"},"modified":"2021-07-30T11:59:35","modified_gmt":"2021-07-30T11:59:35","slug":"carre-cabrito-2","status":"publish","type":"product","link":"https:\/\/www.hermanosmasa.com\/fr\/tienda\/carre-cabrito-2\/","title":{"rendered":"Carr\u00e9 enfant"},"content":{"rendered":"<p>Le carr\u00e9 est demi chevreau (fente de haut en bas) sans jambe, sans \u00e9paule, sans col, sans poitrine et sans jupe. Cela correspond \u00e0 13 c\u00f4tes. La c\u00f4telette de chevreau de lait peut \u00eatre r\u00f4tie en un seul morceau ou les c\u00f4telettes peuvent \u00eatre s\u00e9par\u00e9es pour les d\u00e9guster une \u00e0 une. Nous pouvons vous servir dans les deux sens.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le carr\u00e9 est demi chevreau (fente de haut en bas) sans jambe, sans \u00e9paule, sans col, sans poitrine et sans jupe. Cela correspond \u00e0 13 c\u00f4tes. La c\u00f4telette de chevreau de lait peut \u00eatre r\u00f4tie en un seul morceau ou les c\u00f4telettes peuvent \u00eatre s\u00e9par\u00e9es pour les d\u00e9guster une \u00e0 une. Nous pouvons vous servir [&hellip;]<\/p>\n","protected":false},"featured_media":5815,"comment_status":"open","ping_status":"closed","template":"","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":""},"product_brand":[],"product_cat":[54],"product_tag":[],"class_list":["post-5966","product","type-product","status-publish","has-post-thumbnail","product_cat-cabrito-fr","first","instock","taxable","shipping-taxable","purchasable","product-type-simple"],"_links":{"self":[{"href":"https:\/\/www.hermanosmasa.com\/fr\/wp-json\/wp\/v2\/product\/5966","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.hermanosmasa.com\/fr\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.hermanosmasa.com\/fr\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/www.hermanosmasa.com\/fr\/wp-json\/wp\/v2\/comments?post=5966"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.hermanosmasa.com\/fr\/wp-json\/wp\/v2\/media\/5815"}],"wp:attachment":[{"href":"https:\/\/www.hermanosmasa.com\/fr\/wp-json\/wp\/v2\/media?parent=5966"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.hermanosmasa.com\/fr\/wp-json\/wp\/v2\/product_brand?post=5966"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.hermanosmasa.com\/fr\/wp-json\/wp\/v2\/product_cat?post=5966"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.hermanosmasa.com\/fr\/wp-json\/wp\/v2\/product_tag?post=5966"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}